{"id":15116,"date":"2021-06-29T10:16:01","date_gmt":"2021-06-29T07:16:01","guid":{"rendered":"https:\/\/dev-three.agmastudio.com\/?post_type=wt_project&#038;p=15116"},"modified":"2023-05-22T14:54:28","modified_gmt":"2023-05-22T11:54:28","slug":"arena-mall","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/","title":{"rendered":"Arena Mall"},"content":{"rendered":"","protected":false},"featured_media":15118,"template":"","wt_project_category":[761],"class_list":["post-15116","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arena Mall - Projects | Walltopia Climbing Walls<\/title>\n<meta name=\"description\" content=\"Arena Mall is a Shopping Center with Rope Walls based in Tel Aviv, Israel. Find out more about the project here.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arena Mall\" \/>\n<meta property=\"og:description\" content=\"Arena Mall is a Shopping Center with Rope Walls based in Tel Aviv, Israel. Find out more about the project here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-22T11:54:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030110152\/israel-arena-mall_1200x800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/projects\\\/arena-mall\\\/\",\"url\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/projects\\\/arena-mall\\\/\",\"name\":\"Arena Mall - Projects | Walltopia Climbing Walls\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/projects\\\/arena-mall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/projects\\\/arena-mall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/walltopia.com.cn\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/israel-arena-mall_1200x800.jpg\",\"datePublished\":\"2021-06-29T07:16:01+00:00\",\"dateModified\":\"2023-05-22T11:54:28+00:00\",\"description\":\"Arena Mall is a Shopping Center with Rope Walls based in Tel Aviv, Israel. Find out more about the project here.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/projects\\\/arena-mall\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/projects\\\/arena-mall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/projects\\\/arena-mall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/walltopia.com.cn\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/israel-arena-mall_1200x800.jpg\",\"contentUrl\":\"https:\\\/\\\/walltopia.com.cn\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/israel-arena-mall_1200x800.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/projects\\\/arena-mall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arena Mall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/walltopia.com.cn\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/walltopia-logo.svg\",\"contentUrl\":\"https:\\\/\\\/walltopia.com.cn\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/walltopia-logo.svg\",\"width\":374,\"height\":50,\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com.cn\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arena Mall - Projects | Walltopia Climbing Walls","description":"Arena Mall is a Shopping Center with Rope Walls based in Tel Aviv, Israel. Find out more about the project here.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/","og_locale":"en_US","og_type":"article","og_title":"Arena Mall","og_description":"Arena Mall is a Shopping Center with Rope Walls based in Tel Aviv, Israel. Find out more about the project here.","og_url":"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2023-05-22T11:54:28+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030110152\/israel-arena-mall_1200x800.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/","url":"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/","name":"Arena Mall - Projects | Walltopia Climbing Walls","isPartOf":{"@id":"https:\/\/walltopia.com.cn\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/#primaryimage"},"thumbnailUrl":"https:\/\/walltopia.com.cn\/wp-content\/uploads\/2021\/06\/israel-arena-mall_1200x800.jpg","datePublished":"2021-06-29T07:16:01+00:00","dateModified":"2023-05-22T11:54:28+00:00","description":"Arena Mall is a Shopping Center with Rope Walls based in Tel Aviv, Israel. Find out more about the project here.","breadcrumb":{"@id":"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/#primaryimage","url":"https:\/\/walltopia.com.cn\/wp-content\/uploads\/2021\/06\/israel-arena-mall_1200x800.jpg","contentUrl":"https:\/\/walltopia.com.cn\/wp-content\/uploads\/2021\/06\/israel-arena-mall_1200x800.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com.cn\/en\/projects\/arena-mall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com.cn\/en\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/walltopia.com.cn\/en\/projects\/"},{"@type":"ListItem","position":3,"name":"Arena Mall"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com.cn\/en\/#website","url":"https:\/\/walltopia.com.cn\/en\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com.cn\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com.cn\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/walltopia.com.cn\/en\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com.cn\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/walltopia.com.cn\/en\/#\/schema\/logo\/image\/","url":"https:\/\/walltopia.com.cn\/wp-content\/uploads\/2021\/04\/walltopia-logo.svg","contentUrl":"https:\/\/walltopia.com.cn\/wp-content\/uploads\/2021\/04\/walltopia-logo.svg","width":374,"height":50,"caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com.cn\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com.cn\/en\/wp-json\/wp\/v2\/wt_project\/15116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com.cn\/en\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com.cn\/en\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com.cn\/en\/wp-json\/wp\/v2\/media\/15118"}],"wp:attachment":[{"href":"https:\/\/walltopia.com.cn\/en\/wp-json\/wp\/v2\/media?parent=15116"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com.cn\/en\/wp-json\/wp\/v2\/wt_project_category?post=15116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}